{"id":408,"date":"2022-03-23T15:36:04","date_gmt":"2022-03-23T15:36:04","guid":{"rendered":"https:\/\/bythedots.com\/fr\/trifo-emma-laspirateur-robot-indispensable\/"},"modified":"2025-01-29T11:16:04","modified_gmt":"2025-01-29T11:16:04","slug":"trifo-emma-laspirateur-robot-indispensable","status":"publish","type":"post","link":"https:\/\/www.bythedots.com\/fr\/trifo-emma-laspirateur-robot-indispensable\/","title":{"rendered":"Trifo Emma \u2013 L&#8217;aspirateur robot indispensable"},"content":{"rendered":"<p>Lorsqu&#8217;il s&#8217;agit de toute nouvelle technologie, certains appareils sont plus excitants que d&#8217;autres. Lorsqu&#8217;un nouveau smartphone ou syst\u00e8me de jeu sort, tout le monde en parle. C&#8217;est facile \u00e0 comprendre, car ces appareils sont au c\u0153ur de nos vies. Pensez au nombre de fois par jour que vous sortez votre smartphone. Que vous soyez en train de jouer, de faire des op\u00e9rations bancaires ou de communiquer, vous tirez beaucoup parti de ce petit appareil. Mais le divertissement et les communications ne sont pas l&#8217;alpha et l&#8217;om\u00e9ga de la technologie. Tout aussi souvent, les technologies les plus importantes sont celles qui nous font gagner du temps. Les aspirateurs en sont un bon exemple.<\/p>\n<p>Bien s\u00fbr, un bon aspirateur nettoiera une zone plus facilement et plus efficacement qu&#8217;un aspirateur de qualit\u00e9 inf\u00e9rieure. Mais les robots aspirateurs feront le travail enti\u00e8rement par eux-m\u00eames. Une fois que vous avez termin\u00e9 la configuration initiale, ils n\u00e9cessitent un minimum d&#8217;attention ou d&#8217;implication de votre part. Cela peut vous faire gagner beaucoup de temps et vous \u00e9viter une corv\u00e9e m\u00e9nag\u00e8re fastidieuse. Mais si vous n&#8217;avez pas achet\u00e9 d&#8217;aspirateurs robots depuis un moment, vous pourriez avoir des id\u00e9es fausses. Les premiers robots aspirateurs \u00e9taient inefficaces et fonctionnaient au hasard. Ils nettoieraient trop certaines zones, manqueraient des endroits et se heurteraient \u00e0 vos meubles. Les robots aspirateurs modernes, en revanche, sont un peu plus sophistiqu\u00e9s.<\/p>\n<p>Nous sommes sur le point de tester l&#8217;aspirateur robot Trifo Emma. Il s&#8217;agit d&#8217;un aspirateur robot astucieux avec une application facile \u00e0 utiliser et un moteur un peu plus puissant que la moyenne. Il a une autonomie respectable et une tr\u00e9mie \u00e0 poussi\u00e8re surdimensionn\u00e9e qui peut durer plus longtemps entre les recharges. Il dispose \u00e9galement d&#8217;alertes vocales soign\u00e9es et d&#8217;une fonction de localisation pratique pour ne pas se perdre. Mais la production d&#8217;un robot aspirateur de qualit\u00e9 implique bien plus que cela. Pour vraiment \u00e9valuer ce vide, nous devrons travailler \u00e0 partir de z\u00e9ro, en commen\u00e7ant par la conception physique. Nous devrons examiner la qualit\u00e9 des mat\u00e9riaux et la fa\u00e7on dont ils sont assembl\u00e9s. Nous devrons parler de la dur\u00e9e de vie de la batterie et de la quantit\u00e9 d&#8217;aspiration que vous obtenez. Et bien s\u00fbr, nous devrons passer en revue toutes les fonctionnalit\u00e9s de l&#8217;application. Commen\u00e7ons et voyons ce que nous apprenons\u00a0!<\/p>\n<h3>Conception g\u00e9n\u00e9rale<\/h3>\n<p>L&#8217;aspirateur robot Trifo Emma a une conception en forme de disque, tout comme la plupart des aspirateurs robots. Il a un bo\u00eetier en plastique noir, avec une finition brillante facile \u00e0 nettoyer. Le panneau sup\u00e9rieur a un insert gris en forme de m\u00e9diator, qui est principalement cosm\u00e9tique. Mais vers l&#8217;avant, il y a une paire de boutons de commande simples. Le premier a une ic\u00f4ne d&#8217;alimentation dessus et est utilis\u00e9 pour lancer un cycle de nettoyage. Le second a une ic\u00f4ne de maison dessus et est utilis\u00e9 pour ramener l&#8217;aspirateur \u00e0 sa base. En dehors de cela, tous les contr\u00f4les sont effectu\u00e9s via l&#8217;application. Nous en reparlerons plus dans un instant.<\/p>\n<p>Le bord ext\u00e9rieur du bo\u00eetier est construit comme un pare-chocs, bien qu&#8217;il ne remplisse pas cette fonction. Cela dit, certaines fonctionnalit\u00e9s sont int\u00e9gr\u00e9es dans cette zone. Il y a 2 capteurs de collision sur le pare-chocs pour \u00e9viter les collisions violentes et permettre \u00e0 Emma de se souvenir de la position de collision afin qu&#8217;elle puisse \u00e9viter les obstacles lors du prochain nettoyage.<\/p>\n<p>\u00c0 l&#8217;arri\u00e8re, il y a une paire d&#8217;\u00e9vents, qui servent de sortie d&#8217;air pour le moteur. Le bord d&#8217;attaque est presque enti\u00e8rement occup\u00e9 par un capteur large et haut. Ceci est utilis\u00e9 pour faciliter la navigation, afin qu&#8217;Emma puisse d\u00e9tecter et \u00e9viter les objets. Une chose que nous avons beaucoup appr\u00e9ci\u00e9e est l&#8217;\u00e9conomie du design. \u00c0 3,34 pouces d&#8217;\u00e9paisseur, ce petit aspirateur peut se glisser sous de nombreux meubles. Si vous avez des \u00e9tag\u00e8res ou des canap\u00e9s \u00e0 quelques centim\u00e8tres du sol, vous pourrez facilement nettoyer en dessous.<\/p>\n<p>Malgr\u00e9 son profil mince, Emma est capable de man\u0153uvrer sur des obstacles \u00e9tonnamment grands. Les roues motrices principales sont grandes et robustes et peuvent traverser jusqu&#8217;\u00e0 une transition de 0.8 pouce. La plupart des transitions domestiques mesurent 0,75 pouce ou moins, vous aurez donc rarement \u00e0 vous soucier des probl\u00e8mes de navigation. Cette navigation est assur\u00e9e par une molette plus petite vers l&#8217;avant du bo\u00eetier. La molette de navigation est mont\u00e9e dans son propre sous-bo\u00eetier, qui est motoris\u00e9. Il peut pivoter \u00e0 360 degr\u00e9s, et de cette fa\u00e7on, il peut orienter l&#8217;aspirateur dans la bonne direction.<\/p>\n<p>Entre les deux roues principales se trouve la brosse \u00e0 rouleau principale. Il est divis\u00e9 en trois sections pour \u00e9viter les enchev\u00eatrements, et il est agr\u00e9able et rigide pour p\u00e9n\u00e9trer les tapis. Il est \u00e9galement assez large, avec un chemin de nettoyage de neuf pouces. C&#8217;est large au fur et \u00e0 mesure que les robots aspirateurs vont, et cela permet un nettoyage beaucoup plus efficace qu&#8217;une brosse plus \u00e9troite. En termes simples, vous couvrez plus d&#8217;espace au sol \u00e0 chaque passage. Il existe \u00e9galement un ensemble de brosses horizontales sur les c\u00f4t\u00e9s. Ceux-ci sont con\u00e7us pour les sols solides et balayent comme des pales d&#8217;h\u00e9licopt\u00e8re pour amener les d\u00e9bris vers le centre. En effet, vous \u00e9largissez la zone de couverture et touchez certains points plus d&#8217;une fois.<\/p>\n<p>En plus de l&#8217;aspirateur robot lui-m\u00eame, vous disposez \u00e9galement d&#8217;une station de charge. Il s&#8217;agit d&#8217;un petit bloc noir pos\u00e9 sur votre sol, contre un mur. De l&#8217;avant en bas, une petite plate-forme s&#8217;\u00e9tend, avec des contacts de charge sur le dessus. C&#8217;est l\u00e0 que l&#8217;aspirateur s&#8217;installera lorsqu&#8217;il n&#8217;est pas utilis\u00e9. Choisissez votre emplacement avec soin. Vous ne le voulez pas dans une zone \u00e0 fort trafic, mais vous voulez \u00e9galement \u00eatre \u00e0 proximit\u00e9 d&#8217;une prise de courant.<\/p>\n<h3>Performances sous vide<\/h3>\n<p>Une grande partie de la qualit\u00e9 de tout robot aspirateur se r\u00e9sume \u00e0 la puissance d&#8217;aspiration. Avec un moteur sous-aliment\u00e9, m\u00eame l&#8217;aspirateur le mieux con\u00e7u \u00e9chouera. Heureusement, ce n&#8217;est pas un probl\u00e8me ici. Le moteur d&#8217;Emma a un niveau d&#8217;aspiration maximum de 3 000 Pascals (Pa). L&#8217;aspirateur robot moyen tire \u00e0 environ 2 700 Pa, vous envisagez donc une augmentation d&#8217;environ 10 %. Cet aspirateur fonctionnera sur presque toutes les surfaces, mais pas sur les tapis \u00e0 poils \u00e9pais tr\u00e8s sales. Vous pouvez ramasser des d\u00e9bris comme du riz et des haricots secs, ainsi que des poils d&#8217;animaux, de la poussi\u00e8re et de la salet\u00e9 quotidienne.<\/p>\n<p>Si vous avez besoin de plus d&#8217;aspiration, Trifo fabrique une autre option : la version Emma pour animaux de compagnie. Il y a quelques mises \u00e0 niveau entre la version r\u00e9guli\u00e8re et la version pour animaux de compagnie. Pour commencer, la version pour animaux de compagnie est nettement plus puissante, avec une puissance d&#8217;aspiration maximale de 4 000 Pa. Cela vous permet de l&#8217;utiliser sur des tapis \u00e0 poils \u00e9pais, tout en le rendant plus efficace dans l&#8217;ensemble. De plus, la brosse et l&#8217;ouverture de l&#8217;aspirateur sont sp\u00e9cialement con\u00e7ues pour traiter les poils d&#8217;animaux. En fait, l&#8217;\u00e9dition Pet est m\u00eame livr\u00e9e avec un extracteur de poils d&#8217;animaux sans brosse suppl\u00e9mentaire, dot\u00e9 d&#8217;une fonction anti-nouage. Cela signifie moins d&#8217;enchev\u00eatrements et moins de colmatage, vous n&#8217;avez donc pas \u00e0 interagir avec l&#8217;aspirateur aussi souvent.<\/p>\n<p>La batterie interne rechargeable a une capacit\u00e9 de 2 600 mAh. Cela \u00e9quivaut \u00e0 environ 110 minutes d&#8217;utilisation, mais cela d\u00e9pend beaucoup de la fa\u00e7on dont l&#8217;aspirateur est utilis\u00e9. Parce que la vitesse du moteur est r\u00e9glable, vous obtiendrez plus ou moins selon la vitesse \u00e0 laquelle vous vous trouvez. Mais si vous nettoyez un \u00e9quilibre ordinaire de tapis et de surfaces nues, 110 minutes sont assez pr\u00e9cises. C&#8217;est plus que suffisant pour nettoyer la plupart des maisons et pour couvrir la plupart des plans d&#8217;\u00e9tage.<\/p>\n<p>Mais que se passe-t-il si votre maison est sur le grand c\u00f4t\u00e9 ? Dans ce cas, vous n&#8217;avez pas \u00e0 vous soucier du fait que le vide saute certaines zones. Au lieu de cela, lorsque la batterie est faible, il reviendra automatiquement \u00e0 la base. Une fois qu&#8217;il est compl\u00e8tement charg\u00e9, il repart et reprend le nettoyage l\u00e0 o\u00f9 il s&#8217;est arr\u00eat\u00e9.<\/p>\n<p>Une autre chose \u00e0 noter \u00e0 propos d&#8217;Emma est qu&#8217;elle poss\u00e8de un tr\u00e8s grand bac \u00e0 poussi\u00e8re, d&#8217;une capacit\u00e9 de 600 ml. En comparaison, les poubelles ont tendance \u00e0 se situer dans la plage de 400 ml. C&#8217;est beaucoup d&#8217;espace et suffisant pour plusieurs nettoyages, selon la taille du plan d&#8217;\u00e9tage. La poubelle est principalement transparente, avec un couvercle noir qui s&#8217;ouvre compl\u00e8tement pour cr\u00e9er une grande ouverture. Cela facilite le vidage et vous n&#8217;avez pas \u00e0 vous soucier de l&#8217;agglutination des d\u00e9bris et de l&#8217;obstruction de l&#8217;ouverture.<\/p>\n<h3>Configuration et utilisation quotidienne<\/h3>\n<p>Comme nous l&#8217;avons d\u00e9j\u00e0 mentionn\u00e9, les aspirateurs robots modernes offrent beaucoup plus de performances que les anciens. Le Trifo Emma profite de la technologie moderne pour pousser les performances de l&#8217;aspirateur \u00e0 la limite. Pour commencer, vous avez la barre de capteur sur le devant du bo\u00eetier. Lors de la premi\u00e8re ex\u00e9cution d&#8217;Emma, \u200b\u200bil semblera fonctionner de mani\u00e8re al\u00e9atoire. Mais ce qu&#8217;il fait, c&#8217;est utiliser le capteur pour construire une carte de votre maison. De cette fa\u00e7on, il sait o\u00f9 il doit nettoyer et peut d\u00e9cider de l&#8217;itin\u00e9raire le plus efficace. M\u00eame apr\u00e8s avoir cr\u00e9\u00e9 une carte, la barre de d\u00e9tection restera active. De cette fa\u00e7on, il peut \u00e9viter les meubles, les animaux domestiques et autres objets mobiles.<\/p>\n<p>Le capteur principal est assist\u00e9 d&#8217;un ensemble de six capteurs anti-chute, situ\u00e9s au bas du bo\u00eetier. Ceux-ci surveillent les chutes telles que les marches ou les bords de balcon. De cette fa\u00e7on, vous n&#8217;avez pas \u00e0 vous soucier du vide en passant par-dessus un bord. En prime, l&#8217;IA donnera des annonces vocales si le vide est en difficult\u00e9. Vous entendrez une alerte si Emma est bloqu\u00e9e, ou s&#8217;il y a un bourrage ou un autre probl\u00e8me.<\/p>\n<p>L&#8217;application pour smartphone est facile \u00e0 installer et facile \u00e0 coupler avec votre aspirateur particulier. Une fois install\u00e9, vous pourrez profiter de plusieurs autres fonctionnalit\u00e9s utiles. Vous pouvez afficher la carte de votre maison et voir l&#8217;emplacement de votre aspirateur. De plus, vous pouvez r\u00e9gler l&#8217;aspirateur pour qu&#8217;il fonctionne selon un horaire, afin qu&#8217;il fonctionne au moment qui vous convient le mieux. Vous pouvez r\u00e9gler l&#8217;aspiration en fonction des types de surfaces que vous nettoyez. Vous pouvez m\u00eame coupler avec Alexa ou Google Assistant. N&#8217;oubliez pas qu&#8217;Emma a besoin d&#8217;une bande WiFi de 2,4 GHz pour se connecter.<\/p>\n<h3>Verdict final<\/h3>\n<p>Alors, l&#8217;aspirateur robot Trifo Emma vaut-il votre temps et votre argent\u00a0? Pour la plupart, il est tr\u00e8s bien con\u00e7u. Il a un profil mince, mais peut toujours naviguer dans de grandes transitions. Il a beaucoup d&#8217;aspiration et un grand bac \u00e0 poussi\u00e8re. Et l&#8217;application et les fonctionnalit\u00e9s de navigation sont assez bien agenc\u00e9es. Dans l&#8217;ensemble, nous avons \u00e9t\u00e9 tr\u00e8s satisfaits de ce que nous avons vu.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu&#8217;il s&#8217;agit de toute nouvelle technologie, certains appareils sont plus excitants que d&#8217;autres. Lorsqu&#8217;un nouveau smartphone ou syst\u00e8me de jeu sort, tout le monde en parle. C&#8217;est facile \u00e0 comprendre,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"powerkit_post_featured":[],"class_list":{"0":"post-408","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news"},"_links":{"self":[{"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/posts\/408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/comments?post=408"}],"version-history":[{"count":1,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/posts\/408\/revisions"}],"predecessor-version":[{"id":431,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/posts\/408\/revisions\/431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/media\/409"}],"wp:attachment":[{"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/media?parent=408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/categories?post=408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/tags?post=408"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/www.bythedots.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}